{"id":888,"date":"2023-12-03T11:58:00","date_gmt":"2023-12-03T10:58:00","guid":{"rendered":"https:\/\/iteadjoseph.com\/?p=888"},"modified":"2024-03-15T18:02:42","modified_gmt":"2024-03-15T17:02:42","slug":"hl-bernhard-von-clairvaux","status":"publish","type":"post","link":"https:\/\/iteadjoseph.com\/es\/hl-bernhard-von-clairvaux\/","title":{"rendered":"Hl. Bernhard von Clairvaux"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"1024\" src=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-740x1024.jpg\" alt=\"\" class=\"wp-image-889\" style=\"width:354px;height:auto\" srcset=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-740x1024.jpg 740w, https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-217x300.jpg 217w, https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-768x1063.jpg 768w, https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg 826w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-left\">&#8222;<em>Wahrhaft n\u00e4mlich aus dem Hause Davids, wahrhaft stammte aus k\u00f6niglichem Geschlecht dieser Mann Joseph, edel von Geburt, noch edler nach Charakter und Sinnesart. Ganz ein Sohn Davids, der von seinem Vater David nicht entartet ist. Ganz und gar, sage ich, ein Sohn Davids, nicht nur dem Fleische nach, sondern auch dem Glauben nach, der Heiligkeit nach, der Hingabe nach, den wie einen zweiten David der Herr ganz nach seinem Herzen befunden hat, dem er getrost das heiligste und innerste Geheimnis seines Herzens anvertrauen konnte, dem er wie einem zweiten David das Dunkle und Verborgene seiner Weisheit geoffenbart und verg\u00f6nnt hat, das Geheimnis zu erkennen, das keiner der Gro\u00dfen dieser Welt erkannt hat;dem endlich gegeben wurde, was viele K\u00f6nige und Propheten, obwohl sie es sehen wollten, nicht sahen, h\u00f6ren wollten, aber nicht h\u00f6rten; nicht nur sehen und h\u00f6ren, sondern auch tragen, emporheben, umarmen, k\u00fcssen, ern\u00e4hren und beh\u00fcten. Aber nicht nur von Joseph, sondern auch von Maria muss man glauben, dass sie aus dem Hause David stammte. Anderenfalls w\u00e4re sie nicht einem Manne aus dem Hause Davids verlobt worden, wenn sie nicht selbst aus dem Hause Davids gewesen w\u00e4re. Beide also waren aus dem Hause David; aber in der einen ist die Wahrheit erf\u00fcllt worden, die der Herr dem David verhie\u00df, der andere war Mitwisser und Zeuge der Erf\u00fcllung der Verhei\u00dfung.<\/em>&#8222;<\/p>\n<cite>~ aus der <em>Homilia 2 super Missus est<\/em><\/cite><\/blockquote>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<p><em><strong><em><strong><strong><em>Derzeit befindet sich unsere Webseite im Aufbau. Dieser Artikel <em>\u00fcbe<\/em><\/em><\/strong><\/strong><\/em><\/strong><\/em><strong><em>r den wichtigen Beitrag des hl. Bernhard von Clairvaux zur Entwicklung der Josephsverehrung<\/em><\/strong><em><strong><em><strong><strong> <em>wird noch in den n\u00e4chsten Wochen und Monaten folgen. Aus der Reihe der Heiligen-Artikel ist nach aktuellem Stand (M\u00e4rz 2024) nur derjenige \u00fcber den <a href=\"https:\/\/iteadjoseph.com\/es\/2023\/12\/07\/hl-philipp-neri\/\" data-type=\"link\" data-id=\"https:\/\/iteadjoseph.com\/2023\/12\/07\/hl-philipp-neri\/\">hl. Philipp Neri <\/a>fertiggestellt. Abonnieren Sie gerne unseren <a href=\"https:\/\/iteadjoseph.com\/es\/participate\/#newsletter\" data-type=\"link\" data-id=\"https:\/\/iteadjoseph.com\/participate\/#newsletter\">Newsletter<\/a>, um \u00fcber neue Beitr\u00e4ge auf dem Laufenden zu bleiben!<\/em> <\/strong><\/strong><\/em><\/strong><\/em><\/p>\n\n\n\n<p>Der hl. Bernhard von Clairvaux (1090-1153) gilt als &#8222;letzter der V\u00e4ter&#8220; und unter ihnen nicht der Geringste: Wendepunkt \/\/ nochmal mit den Augen der Kirchenv\u00e4ter auf den hl. Joseph, insofern mehr als Nebenprodukt und keine aktive Verehrung, aber doch auch schon mit der neu akzentuierten Fr\u00f6mmigkeit des hohen Mittelalters, die sich verst\u00e4rkt f\u00fcr das Leben Jesu und damit auch f\u00fcr Maria und Joseph interessierte. Der hl. Bernhard gilt ja auch als &#8222;Doctor Marianus&#8220;, er pr\u00e4gte das Wort &#8222;De Maria numquam satis&#8220;. Seine Predigten \u00fcber das Hohelied&#8230;affektive, mystische Fr\u00f6mmigkeit<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>markiert einen Wendepunkt in der <a href=\"https:\/\/iteadjoseph.com\/es\/index.php\/geschichte\/\" data-type=\"link\" data-id=\"https:\/\/iteadjoseph.com\/index.php\/geschichte\/\">Geschichte der Josephsverehrung<\/a>. Im Hochmittelalter wendet sich die Fr\u00f6mmigkeit st\u00e4rker der Menschheit Jesu und seinem irdischen Leben zu, und damit r\u00fccken auch Maria und Joseph st\u00e4rker in den Fokus. Besonders die Marienfr\u00f6mmigkeit intensiviert sich, und in ihrem Windschatten widmet man man auch ihrem Br\u00e4utigam etwas gr\u00f6\u00dfere Aufmerksamkeit. <\/p>\n\n\n\n<p>Mit ihm beginnt der hl. Joseph in den Fokus zu r\u00fccken (Seitenschwenk Marienverehrung Hochmittelalter)) \/\/ 1. Patristik\/Fr\u00fchmittelalter, 2. Mittelalter\/Neuzeit \/\/ Umso bemerkenswerter, weil &#8222;letzter der V\u00e4ter&#8220;, und damit paradigmatisches Bindegleid der Epochen\/\/<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8222;Wahrhaft n\u00e4mlich aus dem Hause Davids, wahrhaft stammte aus k\u00f6niglichem Geschlecht dieser Mann Joseph, edel von Geburt, noch edler nach Charakter und Sinnesart. Ganz ein Sohn Davids, der von seinem Vater David nicht entartet ist. Ganz und gar, sage ich, ein Sohn Davids, nicht nur dem Fleische nach, sondern auch dem Glauben nach, der Heiligkeit [&hellip;]<\/p>","protected":false},"author":2,"featured_media":889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saints"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hl. Bernhard von Clairvaux - Ite Ad Joseph<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iteadjoseph.com\/es\/hl-bernhard-von-clairvaux\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hl. Bernhard von Clairvaux - Ite Ad Joseph\" \/>\n<meta property=\"og:description\" content=\"&#8222;Wahrhaft n\u00e4mlich aus dem Hause Davids, wahrhaft stammte aus k\u00f6niglichem Geschlecht dieser Mann Joseph, edel von Geburt, noch edler nach Charakter und Sinnesart. Ganz ein Sohn Davids, der von seinem Vater David nicht entartet ist. Ganz und gar, sage ich, ein Sohn Davids, nicht nur dem Fleische nach, sondern auch dem Glauben nach, der Heiligkeit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iteadjoseph.com\/es\/hl-bernhard-von-clairvaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Ite Ad Joseph\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-03T10:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-15T17:02:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"826\" \/>\n\t<meta property=\"og:image:height\" content=\"1143\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nikolas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nikolas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/\"},\"author\":{\"name\":\"nikolas\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/8976e7ed2d7c322ae36a2f9566dbc854\"},\"headline\":\"Hl. Bernhard von Clairvaux\",\"datePublished\":\"2023-12-03T10:58:00+00:00\",\"dateModified\":\"2024-03-15T17:02:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/\"},\"wordCount\":501,\"image\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hl.-Bernhard-von-Clairvaux.jpg\",\"articleSection\":[\"Heilige\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/\",\"name\":\"Hl. Bernhard von Clairvaux - Ite Ad Joseph\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hl.-Bernhard-von-Clairvaux.jpg\",\"datePublished\":\"2023-12-03T10:58:00+00:00\",\"dateModified\":\"2024-03-15T17:02:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/8976e7ed2d7c322ae36a2f9566dbc854\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hl.-Bernhard-von-Clairvaux.jpg\",\"contentUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hl.-Bernhard-von-Clairvaux.jpg\",\"width\":826,\"height\":1143},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-bernhard-von-clairvaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/iteadjoseph.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hl. Bernhard von Clairvaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#website\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/\",\"name\":\"Ite Ad Joseph\",\"description\":\"Eine Webseite zur Verbreitung der Verehrung des Hl. Josephs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iteadjoseph.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/8976e7ed2d7c322ae36a2f9566dbc854\",\"name\":\"nikolas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g\",\"caption\":\"nikolas\"},\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/es\\\/author\\\/nikolas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hl. Bernhard von Clairvaux - Ite Ad Joseph","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iteadjoseph.com\/es\/hl-bernhard-von-clairvaux\/","og_locale":"es_ES","og_type":"article","og_title":"Hl. Bernhard von Clairvaux - Ite Ad Joseph","og_description":"&#8222;Wahrhaft n\u00e4mlich aus dem Hause Davids, wahrhaft stammte aus k\u00f6niglichem Geschlecht dieser Mann Joseph, edel von Geburt, noch edler nach Charakter und Sinnesart. Ganz ein Sohn Davids, der von seinem Vater David nicht entartet ist. Ganz und gar, sage ich, ein Sohn Davids, nicht nur dem Fleische nach, sondern auch dem Glauben nach, der Heiligkeit [&hellip;]","og_url":"https:\/\/iteadjoseph.com\/es\/hl-bernhard-von-clairvaux\/","og_site_name":"Ite Ad Joseph","article_published_time":"2023-12-03T10:58:00+00:00","article_modified_time":"2024-03-15T17:02:42+00:00","og_image":[{"width":826,"height":1143,"url":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg","type":"image\/jpeg"}],"author":"nikolas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nikolas","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/#article","isPartOf":{"@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/"},"author":{"name":"nikolas","@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/8976e7ed2d7c322ae36a2f9566dbc854"},"headline":"Hl. Bernhard von Clairvaux","datePublished":"2023-12-03T10:58:00+00:00","dateModified":"2024-03-15T17:02:42+00:00","mainEntityOfPage":{"@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/"},"wordCount":501,"image":{"@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/#primaryimage"},"thumbnailUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg","articleSection":["Heilige"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/","url":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/","name":"Hl. Bernhard von Clairvaux - Ite Ad Joseph","isPartOf":{"@id":"https:\/\/iteadjoseph.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/#primaryimage"},"image":{"@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/#primaryimage"},"thumbnailUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg","datePublished":"2023-12-03T10:58:00+00:00","dateModified":"2024-03-15T17:02:42+00:00","author":{"@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/8976e7ed2d7c322ae36a2f9566dbc854"},"breadcrumb":{"@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/#primaryimage","url":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg","contentUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg","width":826,"height":1143},{"@type":"BreadcrumbList","@id":"https:\/\/iteadjoseph.com\/hl-bernhard-von-clairvaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/iteadjoseph.com\/"},{"@type":"ListItem","position":2,"name":"Hl. Bernhard von Clairvaux"}]},{"@type":"WebSite","@id":"https:\/\/iteadjoseph.com\/#website","url":"https:\/\/iteadjoseph.com\/","name":"Ite Ad Joseph","description":"Eine Webseite zur Verbreitung der Verehrung des Hl. Josephs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iteadjoseph.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/8976e7ed2d7c322ae36a2f9566dbc854","name":"nikolas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g","caption":"nikolas"},"url":"https:\/\/iteadjoseph.com\/es\/author\/nikolas\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg",826,1143,false],"thumbnail":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-150x150.jpg",150,150,true],"medium":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-217x300.jpg",217,300,true],"medium_large":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-768x1063.jpg",768,1063,true],"large":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux-740x1024.jpg",740,1024,true],"1536x1536":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg",826,1143,false],"2048x2048":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg",826,1143,false],"trp-custom-language-flag":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/01\/Hl.-Bernhard-von-Clairvaux.jpg",9,12,false]},"uagb_author_info":{"display_name":"nikolas","author_link":"https:\/\/iteadjoseph.com\/es\/author\/nikolas\/"},"uagb_comment_info":0,"uagb_excerpt":"&#8222;Wahrhaft n\u00e4mlich aus dem Hause Davids, wahrhaft stammte aus k\u00f6niglichem Geschlecht dieser Mann Joseph, edel von Geburt, noch edler nach Charakter und Sinnesart. Ganz ein Sohn Davids, der von seinem Vater David nicht entartet ist. Ganz und gar, sage ich, ein Sohn Davids, nicht nur dem Fleische nach, sondern auch dem Glauben nach, der Heiligkeit&hellip;","_links":{"self":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":9,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":1934,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts\/888\/revisions\/1934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/media\/889"}],"wp:attachment":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/tags?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}