{"id":351,"date":"2023-12-04T20:14:09","date_gmt":"2023-12-04T19:14:09","guid":{"rendered":"https:\/\/iteadjoseph.com\/?p=351"},"modified":"2025-03-20T19:47:27","modified_gmt":"2025-03-20T18:47:27","slug":"schutzmantelandacht-zu-ehren-des-hl-joseph","status":"publish","type":"post","link":"https:\/\/iteadjoseph.com\/es\/schutzmantelandacht-zu-ehren-des-hl-joseph\/","title":{"rendered":"Novena al Sagrado Manto de San Jos\u00e9"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg\" alt=\"\" class=\"wp-image-7\" style=\"width:468px;height:auto\"\/><\/figure>\n\n\n\n<p>Die Schutzmantelnovene ist eine au\u00dfergew\u00f6hnliche Andachts\u00fcbung zu Ehren des Heiligen Joseph zur Erlangung seiner besonderen F\u00fcrsprache in einem gro\u00dfen Anliegen und wird w\u00e4hrend 30 Tagen gebetet. Unz\u00e4hlig sind die Gebetserh\u00f6rungen und Gnaden, die mit diesem unendlich m\u00e4chtigen Novenengebet verbunden sind.<\/p>\n\n\n\n<p>Open or download the complete Holy Cloak Novena at the following link:<\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-e6938e5c-56cc-4010-9df1-8c8695c51cde\" href=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/03\/Holy-Cloak-Novena-in-Honour-of-St-Joseph.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Holy-Cloak-Novena<\/a><a href=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2024\/03\/Holy-Cloak-Novena-in-Honour-of-St-Joseph.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-e6938e5c-56cc-4010-9df1-8c8695c51cde\">Download<\/a><\/div>\n\n\n\n<p class=\"has-text-align-center\"><em>Most Pure Heart of Joseph, pray for us!<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Die Schutzmantelnovene ist eine au\u00dfergew\u00f6hnliche Andachts\u00fcbung zu Ehren des Heiligen Joseph zur Erlangung seiner besonderen F\u00fcrsprache in einem gro\u00dfen Anliegen und wird w\u00e4hrend 30 Tagen gebetet. Unz\u00e4hlig sind die Gebetserh\u00f6rungen und Gnaden, die mit diesem unendlich m\u00e4chtigen Novenengebet verbunden sind. Die vollst\u00e4ndige Schutzmantelnovene k\u00f6nnen Sie unter folgendem Link \u00f6ffnen bzw. herunterladen: Reinstes Herz des hl. [&hellip;]<\/p>","protected":false},"author":1,"featured_media":7,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prayers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schutzmantelandacht zu Ehren des Hl. Joseph - Ite Ad Joseph<\/title>\n<meta name=\"description\" content=\"Es gibt kein Anliegen, das der hl. Joseph nicht f\u00fcr uns l\u00f6sen k\u00f6nnte, wenn wir 30 Tage lang die Schutzmantelandacht zu seinen Ehren beten!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iteadjoseph.com\/es\/schutzmantelandacht-zu-ehren-des-hl-joseph\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schutzmantelandacht zu Ehren des Hl. Joseph - Ite Ad Joseph\" \/>\n<meta property=\"og:description\" content=\"Es gibt kein Anliegen, das der hl. Joseph nicht f\u00fcr uns l\u00f6sen k\u00f6nnte, wenn wir 30 Tage lang die Schutzmantelandacht zu seinen Ehren beten!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iteadjoseph.com\/es\/schutzmantelandacht-zu-ehren-des-hl-joseph\/\" \/>\n<meta property=\"og:site_name\" content=\"Ite Ad Joseph\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T19:14:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T18:47:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Josef\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Josef\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/\"},\"author\":{\"name\":\"Josef\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/f1e5f030bcee369104a208db3d9f469e\"},\"headline\":\"Schutzmantelandacht zu Ehren des Hl. Joseph\",\"datePublished\":\"2023-12-04T19:14:09+00:00\",\"dateModified\":\"2025-03-20T18:47:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/\"},\"wordCount\":78,\"image\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-1694809381-scaled.jpg\",\"articleSection\":[\"Gebete\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/\",\"name\":\"Schutzmantelandacht zu Ehren des Hl. Joseph - Ite Ad Joseph\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-1694809381-scaled.jpg\",\"datePublished\":\"2023-12-04T19:14:09+00:00\",\"dateModified\":\"2025-03-20T18:47:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/f1e5f030bcee369104a208db3d9f469e\"},\"description\":\"Es gibt kein Anliegen, das der hl. Joseph nicht f\u00fcr uns l\u00f6sen k\u00f6nnte, wenn wir 30 Tage lang die Schutzmantelandacht zu seinen Ehren beten!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-1694809381-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-1694809381-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"Photo by Sergei Sushchik on Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/schutzmantelandacht-zu-ehren-des-hl-joseph\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/iteadjoseph.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schutzmantelandacht zu Ehren des Hl. Joseph\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#website\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/\",\"name\":\"Ite Ad Joseph\",\"description\":\"Eine Webseite zur Verbreitung der Verehrung des Hl. Josephs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iteadjoseph.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/f1e5f030bcee369104a208db3d9f469e\",\"name\":\"Josef\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e64b00a0577679601eb1bf7703e68c1131790a4c8a062a15a81be31cda36f212?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e64b00a0577679601eb1bf7703e68c1131790a4c8a062a15a81be31cda36f212?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e64b00a0577679601eb1bf7703e68c1131790a4c8a062a15a81be31cda36f212?s=96&d=mm&r=g\",\"caption\":\"Josef\"},\"sameAs\":[\"https:\\\/\\\/iteadjoseph.com\"],\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/es\\\/author\\\/josef-finkbeiner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schutzmantelandacht zu Ehren des Hl. Joseph - Ite Ad Joseph","description":"Es gibt kein Anliegen, das der hl. Joseph nicht f\u00fcr uns l\u00f6sen k\u00f6nnte, wenn wir 30 Tage lang die Schutzmantelandacht zu seinen Ehren beten!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iteadjoseph.com\/es\/schutzmantelandacht-zu-ehren-des-hl-joseph\/","og_locale":"es_ES","og_type":"article","og_title":"Schutzmantelandacht zu Ehren des Hl. Joseph - Ite Ad Joseph","og_description":"Es gibt kein Anliegen, das der hl. Joseph nicht f\u00fcr uns l\u00f6sen k\u00f6nnte, wenn wir 30 Tage lang die Schutzmantelandacht zu seinen Ehren beten!","og_url":"https:\/\/iteadjoseph.com\/es\/schutzmantelandacht-zu-ehren-des-hl-joseph\/","og_site_name":"Ite Ad Joseph","article_published_time":"2023-12-04T19:14:09+00:00","article_modified_time":"2025-03-20T18:47:27+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg","type":"image\/jpeg"}],"author":"Josef","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Josef","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/#article","isPartOf":{"@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/"},"author":{"name":"Josef","@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/f1e5f030bcee369104a208db3d9f469e"},"headline":"Schutzmantelandacht zu Ehren des Hl. Joseph","datePublished":"2023-12-04T19:14:09+00:00","dateModified":"2025-03-20T18:47:27+00:00","mainEntityOfPage":{"@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/"},"wordCount":78,"image":{"@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/#primaryimage"},"thumbnailUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg","articleSection":["Gebete"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/","url":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/","name":"Schutzmantelandacht zu Ehren des Hl. Joseph - Ite Ad Joseph","isPartOf":{"@id":"https:\/\/iteadjoseph.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/#primaryimage"},"image":{"@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/#primaryimage"},"thumbnailUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg","datePublished":"2023-12-04T19:14:09+00:00","dateModified":"2025-03-20T18:47:27+00:00","author":{"@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/f1e5f030bcee369104a208db3d9f469e"},"description":"Es gibt kein Anliegen, das der hl. Joseph nicht f\u00fcr uns l\u00f6sen k\u00f6nnte, wenn wir 30 Tage lang die Schutzmantelandacht zu seinen Ehren beten!","breadcrumb":{"@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/#primaryimage","url":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg","contentUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg","width":1920,"height":2560,"caption":"Photo by Sergei Sushchik on Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/iteadjoseph.com\/schutzmantelandacht-zu-ehren-des-hl-joseph\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/iteadjoseph.com\/"},{"@type":"ListItem","position":2,"name":"Schutzmantelandacht zu Ehren des Hl. Joseph"}]},{"@type":"WebSite","@id":"https:\/\/iteadjoseph.com\/#website","url":"https:\/\/iteadjoseph.com\/","name":"Ite Ad Joseph","description":"Eine Webseite zur Verbreitung der Verehrung des Hl. Josephs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iteadjoseph.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/f1e5f030bcee369104a208db3d9f469e","name":"Josef","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e64b00a0577679601eb1bf7703e68c1131790a4c8a062a15a81be31cda36f212?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e64b00a0577679601eb1bf7703e68c1131790a4c8a062a15a81be31cda36f212?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e64b00a0577679601eb1bf7703e68c1131790a4c8a062a15a81be31cda36f212?s=96&d=mm&r=g","caption":"Josef"},"sameAs":["https:\/\/iteadjoseph.com"],"url":"https:\/\/iteadjoseph.com\/es\/author\/josef-finkbeiner\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",1920,2560,false],"thumbnail":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",113,150,false],"medium":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",225,300,false],"medium_large":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",768,1024,false],"large":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",768,1024,false],"1536x1536":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",1152,1536,false],"2048x2048":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",1536,2048,false],"trp-custom-language-flag":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/09\/image-1694809381-scaled.jpg",9,12,false]},"uagb_author_info":{"display_name":"Josef","author_link":"https:\/\/iteadjoseph.com\/es\/author\/josef-finkbeiner\/"},"uagb_comment_info":0,"uagb_excerpt":"Die Schutzmantelnovene ist eine au\u00dfergew\u00f6hnliche Andachts\u00fcbung zu Ehren des Heiligen Joseph zur Erlangung seiner besonderen F\u00fcrsprache in einem gro\u00dfen Anliegen und wird w\u00e4hrend 30 Tagen gebetet. Unz\u00e4hlig sind die Gebetserh\u00f6rungen und Gnaden, die mit diesem unendlich m\u00e4chtigen Novenengebet verbunden sind. Die vollst\u00e4ndige Schutzmantelnovene k\u00f6nnen Sie unter folgendem Link \u00f6ffnen bzw. herunterladen: Reinstes Herz des hl.&hellip;","_links":{"self":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":10,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts\/351\/revisions"}],"predecessor-version":[{"id":2083,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/posts\/351\/revisions\/2083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/media\/7"}],"wp:attachment":[{"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/media?parent=351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/categories?post=351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iteadjoseph.com\/es\/wp-json\/wp\/v2\/tags?post=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}