{"id":725,"date":"2023-12-07T08:14:25","date_gmt":"2023-12-07T07:14:25","guid":{"rendered":"https:\/\/iteadjoseph.com\/?p=725"},"modified":"2024-03-05T20:14:04","modified_gmt":"2024-03-05T19:14:04","slug":"hl-philipp-neri","status":"publish","type":"post","link":"https:\/\/iteadjoseph.com\/en\/hl-philipp-neri\/","title":{"rendered":"Hl. Philipp Neri"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif\" alt=\"\" class=\"wp-image-726\" style=\"width:404px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">\u201eAuch sollen wir den glorreichen heiligen Joseph, den Br\u00e4utigam der allerseligsten Jungfrau, mit tiefer Andacht verehren. Unaussprechlich viel Gutes entspringt f\u00fcr die Seele aus der Andacht zu diesem gro\u00dfen Heiligen.\u201c<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>~ aus der \u201eSchule des hl. Philipp\u201c<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\">Der hl. Philipp Neri (1515\u20131595) gilt als \u201ezweiter Apostel Roms\u201c. Eigentlich wollte er dem hl. Franz Xaver nach Indien folgen, um als Missionar die Ungl\u00e4ubigen zu bekehren. Doch der Abt von Tre Fontane, ein heiligm\u00e4\u00dfiger und weiser Beichtvater \u00fcberzeugte ihn, dass seine Berufung im Herzen der Christenheit lag: \u201eDein Indien ist Rom!\u201c So verblieb der geb\u00fcrtige Florentiner, der im Alter von 19 Jahren nach Rom gezogen war, bis an sein Lebensende in der Ewigen Stadt. Seinem apostolischen Wirken ist es zu verdanken, dass Rom, das in dieser Zeit der Renaissance teils in schlimmster Sittenlosigkeit versunken war, \u201eein zweites Mal\u201c bekehrt wurde.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Was wenige wissen: Dieser charismatische, fr\u00f6hliche und witzige Heilige war ein gro\u00dfer Mystiker. Viele seiner Sp\u00e4\u00dfe und Possen hatten nicht nur einen \u201eapostolischen Nutzen\u201c, indem sie dem Christentum ein fr\u00f6hliches Antlitz verleihen wollten. Sie dienten vor allem dem Zweck, seine gro\u00dfe Heiligkeit gleichsam zu verdecken. Der hl. Philipp wusste, dass wahre Heiligkeit in der Verborgenheit zu suchen war. W\u00e4hrend seiner ersten Jahre in der gro\u00dfen Stadt lebte er phasenweise als Eremit. Ihn zog es besonders in die dunklen Tiefen der Katakomben, wo er sich Betrachtungen, Gebeten und Bu\u00df\u00fcbungen hingab. Dort erlebte er auch sein mystisches \u201ePfingstereignis\u201c: Bei einer Nachtwache zu Pfingsten 1544 ergriff der Hl. Geist in Gestalt eines Feuerballs das Herz des hl. Philipp, das seitdem wundersam geweitet war. Auch als er sp\u00e4ter \u2013 erst im Alter von 36 Jahren \u2013 auf Dr\u00e4ngen seines Beichtvaters zum Priester geweiht wurde und fortan als Seelsorger mitten in der Welt wirkte, lebte er doch innerlich weiter als Eremit: Seine Heiligkeit blieb vor der Welt verborgen, indem er vor den Menschen den Narren spielte und daher auch von vielen zun\u00e4chst kaum ernst genommen wurde. Die mystische Tiefe seiner Gottesbeziehung blieb ein Geheimnis.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Freilich nahm seine Heiligkeit so sehr zu, dass sie bald kaum mehr zu verdecken war. Doch je mehr er als Heiliger galt, umso alberner und l\u00e4cherlicher pr\u00e4sentierte er sich vor den Menschen. Durch diese Diskrepanz zwischen der \u00e4u\u00dferlichen Rolle des Narren einerseits und des innerlich verborgenen Mystikers andererseits k\u00f6nnen wir auch erst den Leitspruch des hl. Philipp wirklich verstehen: \u201eAmare nesciri\u201c \u2013 \u201elieben, nicht gekannt zu werden\u201c. Auf den ersten Blick wirkt dieser Leitspruch aus dem Munde eines so leutseligen Priesters v\u00f6llig paradox. Doch w\u00e4hrend dieser exzentrische Priester in ganz Rom stadtbekannt und in aller Munde war, versuchte er zugleich, sein eigentliches Wesen, das unaussprechlich tief von der g\u00f6ttlichen Liebe durchdrungen war, so gut er es eben vermochte, vor den Augen der Welt zu verbergen. Dies ist umso bemerkenswerter, weil er von seiner fr\u00f6hlich-geselligen und charmanten Natur aus eigentlich nicht zur Verborgenheit, sondern im Gegenteil zur Ostentation und Selbstdarstellung veranlagt war. Sein gro\u00dfer \u201eErfolg\u201c als Menschenfischer barg die Versuchung, dies als sein eigenes Verdienst anzusehen \u2013 vielleicht nicht explizit, aber doch so, dass sich bei ihm irgendwann das Gef\u00fchl einschleichen konnte, dass er ein \u201etoller Kerl\u201c war. Er war bei allen beliebt und h\u00e4tte sich in dieser Beliebtheit sozusagen \u201esonnen\u201c k\u00f6nnen; anders gesagt h\u00e4tte er, rein menschlich betrachtet, so ziemlich \u201emit sich selbst zufrieden\u201c sein k\u00f6nnen.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Er hatte jedoch wie sein Zeitgenosse, der hl. Johannes vom Kreuz, erkannt, dass Eitelkeit und Stolz sich auch und gerade da, wo wir Gutes tun, ganz subtil einschleichen, dadurch den Wert eines jeden guten Werkes und am Ende das geistliche Leben \u00fcberhaupt zerst\u00f6ren k\u00f6nnen. Der hl. Philipp entwickelte daher eine umso tiefere Abneigung gegen jede noch so unscheinbare Form der eitlen Selbstliebe und \u00fcbte eine umso gr\u00f6\u00dfere Selbstverleugnung. Daher wollte er lieber als Narr denn als Heiliger gelten. Den Zeugen der von ihm unz\u00e4hlig gewirkten Wunder verbat er streng, anderen davon zu erz\u00e4hlen. Theologisch hochgebildet, gab er sich oft unbedarft und erstaunte umso mehr seine Umgebung, wenn bei seltenen Momenten doch etwas von seinem Wissen durchblitzte. Um nicht einmal den Anschein der Gelehrsamkeit zu geben, verkaufte er einmal alle seine B\u00fccher. In Anwesenheit hochgestellter Pers\u00f6nlichkeiten, die ihm die Aufwartung machten, stellte er sich manchmal geradezu dumm. Er tat alles, um seine Heiligkeit verborgen zu halten.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Damit ist gerade er, der charismatische Gro\u00dfstadtapostel, in gewisser Weise ein besonders treuer Sohn des hl. Joseph gewesen. Der hl. Philipp lehrt uns, wie den Tugenden des hl. Joseph nachzueifern auch mitten in der Welt m\u00f6glich ist. Das Alleinsein mit Christus, stille Verborgenheit und Schlichtheit des Herzens \u2013 all das k\u00f6nnen wir auch dann \u00fcben, wenn wir von geselliger Natur sind und uns mitten im Trubel befinden. Entscheidend sind immer unsere innere Haltung und der Grund unseres Herzens, das Gott allein kennt. Unscheinbare Pflichterf\u00fcllung und dem\u00fctige Selbstverleugnung sind der Schl\u00fcssel zur Heiligkeit, auch wenn diese je nach Pers\u00f6nlichkeit nach au\u00dfen hin eine andere Gestalt annimmt.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Hl. Joseph, bitte f\u00fcr uns!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Hl. Philipp, bitte f\u00fcr uns!<\/em><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Der hl. Philipp lehrt uns, wie wir die Tugenden des hl. Joseph auch inmitten der Welt nachahmen k\u00f6nnen.<\/p>","protected":false},"author":2,"featured_media":726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saints"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hl. Philipp Neri - Ite Ad Joseph<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iteadjoseph.com\/en\/hl-philipp-neri\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hl. Philipp Neri - Ite Ad Joseph\" \/>\n<meta property=\"og:description\" content=\"Der hl. Philipp lehrt uns, wie wir die Tugenden des hl. Joseph auch inmitten der Welt nachahmen k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iteadjoseph.com\/en\/hl-philipp-neri\/\" \/>\n<meta property=\"og:site_name\" content=\"Ite Ad Joseph\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-07T07:14:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T19:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"nikolas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nikolas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/\"},\"author\":{\"name\":\"nikolas\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/8976e7ed2d7c322ae36a2f9566dbc854\"},\"headline\":\"Hl. Philipp Neri\",\"datePublished\":\"2023-12-07T07:14:25+00:00\",\"dateModified\":\"2024-03-05T19:14:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/\"},\"wordCount\":854,\"image\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Philipp-Neri-e1702487520391.gif\",\"articleSection\":[\"Heilige\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/\",\"name\":\"Hl. Philipp Neri - Ite Ad Joseph\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Philipp-Neri-e1702487520391.gif\",\"datePublished\":\"2023-12-07T07:14:25+00:00\",\"dateModified\":\"2024-03-05T19:14:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/8976e7ed2d7c322ae36a2f9566dbc854\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Philipp-Neri-e1702487520391.gif\",\"contentUrl\":\"https:\\\/\\\/iteadjoseph.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Philipp-Neri-e1702487520391.gif\",\"width\":350,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/hl-philipp-neri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/iteadjoseph.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hl. Philipp Neri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#website\",\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/\",\"name\":\"Ite Ad Joseph\",\"description\":\"Eine Webseite zur Verbreitung der Verehrung des Hl. Josephs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iteadjoseph.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iteadjoseph.com\\\/#\\\/schema\\\/person\\\/8976e7ed2d7c322ae36a2f9566dbc854\",\"name\":\"nikolas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g\",\"caption\":\"nikolas\"},\"url\":\"https:\\\/\\\/iteadjoseph.com\\\/en\\\/author\\\/nikolas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hl. Philipp Neri - Ite Ad Joseph","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iteadjoseph.com\/en\/hl-philipp-neri\/","og_locale":"en_US","og_type":"article","og_title":"Hl. Philipp Neri - Ite Ad Joseph","og_description":"Der hl. Philipp lehrt uns, wie wir die Tugenden des hl. Joseph auch inmitten der Welt nachahmen k\u00f6nnen.","og_url":"https:\/\/iteadjoseph.com\/en\/hl-philipp-neri\/","og_site_name":"Ite Ad Joseph","article_published_time":"2023-12-07T07:14:25+00:00","article_modified_time":"2024-03-05T19:14:04+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif","type":"image\/gif"}],"author":"nikolas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nikolas","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/#article","isPartOf":{"@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/"},"author":{"name":"nikolas","@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/8976e7ed2d7c322ae36a2f9566dbc854"},"headline":"Hl. Philipp Neri","datePublished":"2023-12-07T07:14:25+00:00","dateModified":"2024-03-05T19:14:04+00:00","mainEntityOfPage":{"@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/"},"wordCount":854,"image":{"@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/#primaryimage"},"thumbnailUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif","articleSection":["Heilige"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/","url":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/","name":"Hl. Philipp Neri - Ite Ad Joseph","isPartOf":{"@id":"https:\/\/iteadjoseph.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/#primaryimage"},"image":{"@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/#primaryimage"},"thumbnailUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif","datePublished":"2023-12-07T07:14:25+00:00","dateModified":"2024-03-05T19:14:04+00:00","author":{"@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/8976e7ed2d7c322ae36a2f9566dbc854"},"breadcrumb":{"@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iteadjoseph.com\/hl-philipp-neri\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/#primaryimage","url":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif","contentUrl":"https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif","width":350,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/iteadjoseph.com\/hl-philipp-neri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/iteadjoseph.com\/"},{"@type":"ListItem","position":2,"name":"Hl. Philipp Neri"}]},{"@type":"WebSite","@id":"https:\/\/iteadjoseph.com\/#website","url":"https:\/\/iteadjoseph.com\/","name":"Ite Ad Joseph","description":"Eine Webseite zur Verbreitung der Verehrung des Hl. Josephs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iteadjoseph.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/iteadjoseph.com\/#\/schema\/person\/8976e7ed2d7c322ae36a2f9566dbc854","name":"nikolas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64cbcacf1fac477963387e073adce6cefd69133d670a4099af39235c324501d8?s=96&d=mm&r=g","caption":"nikolas"},"url":"https:\/\/iteadjoseph.com\/en\/author\/nikolas\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif",350,350,false],"thumbnail":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391-150x150.gif",150,150,true],"medium":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391-300x300.gif",300,300,true],"medium_large":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif",350,350,false],"large":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif",350,350,false],"1536x1536":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif",350,350,false],"2048x2048":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif",350,350,false],"trp-custom-language-flag":["https:\/\/iteadjoseph.com\/wp-content\/uploads\/2023\/12\/Philipp-Neri-e1702487520391.gif",12,12,false]},"uagb_author_info":{"display_name":"nikolas","author_link":"https:\/\/iteadjoseph.com\/en\/author\/nikolas\/"},"uagb_comment_info":0,"uagb_excerpt":"Der hl. Philipp lehrt uns, wie wir die Tugenden des hl. Joseph auch inmitten der Welt nachahmen k\u00f6nnen.","_links":{"self":[{"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/posts\/725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/comments?post=725"}],"version-history":[{"count":6,"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/posts\/725\/revisions"}],"predecessor-version":[{"id":1745,"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/posts\/725\/revisions\/1745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/media\/726"}],"wp:attachment":[{"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/media?parent=725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/categories?post=725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iteadjoseph.com\/en\/wp-json\/wp\/v2\/tags?post=725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}